{"id":3011,"date":"2022-05-05T09:20:36","date_gmt":"2022-05-05T07:20:36","guid":{"rendered":"https:\/\/plateformes-de-veille.org\/index.php\/2022\/05\/05\/les-veilleurs-et-les-documentalistes-face-au-teletravail\/"},"modified":"2022-05-05T09:20:36","modified_gmt":"2022-05-05T07:20:36","slug":"les-veilleurs-et-les-documentalistes-face-au-teletravail","status":"publish","type":"post","link":"https:\/\/plateformes-de-veille.org\/index.php\/2022\/05\/05\/les-veilleurs-et-les-documentalistes-face-au-teletravail\/","title":{"rendered":"Les veilleurs et les documentalistes face au t\u00e9l\u00e9travail"},"content":{"rendered":"<p>Source : Flux rss &#8211; Veille m\u00e9tier MB via documentation-renseignements on Inoreader<\/p>\n<p><a href=\"https:\/\/www.archimag.com\/veille-documentation\/2022\/05\/04\/veilleurs-documentalistes-face-au-teletravail\" target=\"_blank\" class=\"feedzy-rss-link-icon\" rel=\"noopener\">Read More<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Source : Flux rss &#8211; Veille m\u00e9tier MB via documentation-renseignements on Inoreader Read More<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-3011","post","type-post","status-publish","format-standard","hentry","category-veille-de-mathieu"],"_links":{"self":[{"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/posts\/3011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/comments?post=3011"}],"version-history":[{"count":0,"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/posts\/3011\/revisions"}],"wp:attachment":[{"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/media?parent=3011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/categories?post=3011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plateformes-de-veille.org\/index.php\/wp-json\/wp\/v2\/tags?post=3011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}